{"id":12654,"date":"2022-05-07T18:08:24","date_gmt":"2022-05-07T22:08:24","guid":{"rendered":"http:\/\/www.proforceautomotive.com\/WPCE\/product\/standard-disc-brake-rotor-998\/"},"modified":"2022-05-16T12:52:20","modified_gmt":"2022-05-16T16:52:20","slug":"standard-disc-brake-rotor-998","status":"publish","type":"product","link":"http:\/\/www.proforceautomotive.com\/WPCE\/product\/standard-disc-brake-rotor-998\/","title":{"rendered":"Standard Disc Brake Rotor"},"content":{"rendered":"<table width=\"100%\" border=\"1\" cellpadding=\"4\" cellspacing=\"0\" style=\" font-size:11px;\">\n<tbody>\n<tr>\n<td bgcolor=\"#eeeeee\">Year<\/td>\n<td bgcolor=\"#eeeeee\">Position<\/td>\n<td bgcolor=\"#eeeeee\">Make, Model, SubModel, Engine &#038; More<\/td>\n<td bgcolor=\"#eeeeee\">NOTE<\/td>\n<\/tr>\n<tr>\n<td>1997 1998 1999 2000 2001 2002<\/td>\n<td>Rear<\/td>\n<td>Mazda Millenia Base V6 2.5L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>1997 1998 1999 2000 2002<\/td>\n<td>Rear<\/td>\n<td>Mazda Millenia S V6 2.3L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>1997 1998<\/td>\n<td>Rear<\/td>\n<td>Mazda Millenia L V6 2.5L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2000<\/td>\n<td>Rear<\/td>\n<td>Mazda Millenia Millennium Edition V6 2.3L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2001<\/td>\n<td>Rear<\/td>\n<td>Mazda Millenia Base V6 2.3L<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Year Position Make, Model, SubModel, Engine &#038; More NOTE 1997 1998 1999 2000 2001 2002 Rear Mazda Millenia Base V6 2.5L 1997 1998 1999 2000 2002 Rear Mazda Millenia S V6 2.3L 1997 1998 Rear Mazda Millenia L V6 2.5L 2000 Rear Mazda Millenia Millennium Edition V6 2.3L 2001 Rear Mazda Millenia Base V6 2.3L<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[29],"product_tag":[],"class_list":["post-12654","product","type-product","status-publish","hentry","product_cat-standard-disc-brake-rotor"],"_links":{"self":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product\/12654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/media?parent=12654"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product_cat?post=12654"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product_tag?post=12654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}