{"id":5729,"date":"2022-05-06T10:46:24","date_gmt":"2022-05-06T14:46:24","guid":{"rendered":"http:\/\/www.proforceautomotive.com\/WPCE\/product\/standard-disc-brake-rotor-525\/"},"modified":"2022-05-16T12:19:31","modified_gmt":"2022-05-16T16:19:31","slug":"standard-disc-brake-rotor-525","status":"publish","type":"product","link":"http:\/\/www.proforceautomotive.com\/WPCE\/product\/standard-disc-brake-rotor-525\/","title":{"rendered":"Standard Disc Brake Rotor"},"content":{"rendered":"<table width=\"100%\" border=\"1\" cellpadding=\"4\" cellspacing=\"0\" style=\" font-size:11px;\">\n<tbody>\n<tr>\n<td bgcolor=\"#eeeeee\">Year<\/td>\n<td bgcolor=\"#eeeeee\">Position<\/td>\n<td bgcolor=\"#eeeeee\">Make, Model, SubModel, Engine &#038; More<\/td>\n<td bgcolor=\"#eeeeee\">NOTE<\/td>\n<\/tr>\n<tr>\n<td>2008 2009 2010 2011 2012<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C300 4Matic V6 3.0L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2009 2010 2011 2012<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C300 4Matic Luxury V6 3.0L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2009 2010 2011 2012<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C300 4Matic Sport V6 3.0L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2009 2010 2011<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C300 Sport V6 3.0L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2009 2010<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C300 Base V6 3.0L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2009<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C230 4Matic V6 2.5L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2009<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C230 Base V6 2.5L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2008 2010 2011<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C300 Luxury V6 3.0L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2010 2011<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 4Matic V6 2.5L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2010 2011<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Base V6 2.5L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2012<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Base L4 1.8L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2012<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Luxury L4 1.8L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2012<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Sport L4 1.8L<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>2013 2014<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Luxury L4 1.8L<\/td>\n<td>Luxury Sport<\/td>\n<\/tr>\n<tr>\n<td>2013 2014<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Sport L4 1.8L<\/td>\n<td>Luxury Sport<\/td>\n<\/tr>\n<tr>\n<td>2015<\/td>\n<td>Rear<\/td>\n<td>Mercedes-Benz C250 Base L4 1.8L<\/td>\n<td>without Sport Package<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Year Position Make, Model, SubModel, Engine &#038; More NOTE 2008 2009 2010 2011 2012 Rear Mercedes-Benz C300 4Matic V6 3.0L 2008 2009 2010 2011 2012 Rear Mercedes-Benz C300 4Matic Luxury V6 3.0L 2008 2009 2010 2011 2012 Rear Mercedes-Benz C300 4Matic Sport V6 3.0L 2008 2009 2010 2011 Rear Mercedes-Benz C300 Sport V6 3.0L 2008 [&hellip;]<\/p>\n","protected":false},"featured_media":5728,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[29],"product_tag":[],"class_list":["post-5729","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-standard-disc-brake-rotor"],"_links":{"self":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product\/5729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/media\/5728"}],"wp:attachment":[{"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/media?parent=5729"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product_cat?post=5729"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/www.proforceautomotive.com\/WPCE\/wp-json\/wp\/v2\/product_tag?post=5729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}